{"id":3339,"date":"2018-05-22T11:12:35","date_gmt":"2018-05-22T09:12:35","guid":{"rendered":"https:\/\/gerriets2021.webproofed.de\/de\/?page_id=3339"},"modified":"2023-01-24T16:38:49","modified_gmt":"2023-01-24T15:38:49","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.gerriets-acoustics.com\/pl\/ochrona-danych\/","title":{"rendered":"Ochrona danych"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div id=\"agni-row-96287\" class=\"section-row\" ><div class=\"section-row-bg-container section-row-bg-container-agni-row-96287\"><div class=\"section-row-bg section-row-bg-color \"  ><\/div><\/div><div class=\"container\"><div class=\"vc_row vc_row_fluid \"><div id=\"agni-column-26593\" class=\"wpb_column agni_column_container agni_column vc_column_container vc_col-sm-12\"><div class=\"agni_column-inner vc_column-inner text-left\"  ><div class=\"section-column-bg-container section-column-bg-container-agni-column-26593 \" ><div class=\"section-column-bg section-column-bg-color \"  ><\/div><\/div><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"agni-row-57445\" class=\"section-row\" style=\"margin-top: 5%; \"><div class=\"section-row-bg-container section-row-bg-container-agni-row-57445\"><div class=\"section-row-bg section-row-bg-color \"  ><\/div><\/div><div class=\"container\"><div class=\"vc_row vc_row_fluid vc_row-o-content-top vc_column-gap-30 vc_row-flex\"><div id=\"agni-column-88270\" class=\"wpb_column agni_column_container agni_column vc_column_container vc_col-sm-12\"><div class=\"agni_column-inner vc_column-inner text-left\"  ><div class=\"section-column-bg-container section-column-bg-container-agni-column-88270 \" ><div class=\"section-column-bg section-column-bg-color \"  ><\/div><\/div><div class=\"wpb_wrapper\"><div class=\"agni_custom_heading page-scroll\" ><h2 class=\"vc_custom_heading agni_custom_heading_responsive  agni_custom_heading_content \" style=\"font-size: 60px;color: #666666;text-align: left; \"><span>Datenschutz\u00aderkl\u00e4rung<\/span><\/h2><\/div>\n\t<div id=\"\" class=\"agni_text_column agni-text-block \"  >\n\t\t<div class=\"std\">\n<p><strong>Privatsph\u00e4reneinwilligung<\/strong><\/p>\n<p><a  href=\"#consent-change\" role=\"button\" id=\"rcb-sc-link-change\" data-success-message=\"\" class=\"rcb-sc-link rcb-sc-link-change \">Privatsph\u00e4re-Einstellungen \u00e4ndern<\/a><br \/>\n<a  href=\"#consent-history\" role=\"button\" id=\"rcb-sc-link-history\" data-success-message=\"\" class=\"rcb-sc-link rcb-sc-link-history \">Historie der Privatsph\u00e4re-Einstellungen<\/a><br \/>\n<a  href=\"#consent-revoke\" role=\"button\" id=\"rcb-sc-link-revoke\" data-success-message=\"Sie haben die Einwilligung erfolgreich widerrufen. Die Seite wird nun neu geladen.\" class=\"rcb-sc-link rcb-sc-link-revoke \">Einwilligungen widerrufen<\/a><\/p>\n<p><strong>1 Information \u00fcber die Erhebung personenbezogener Daten<\/strong><\/p>\n<p>(1) Im Folgenden informieren wir \u00fcber die Erhebung personenbezogener Daten bei Nutzung unserer Website. Personenbezogene Daten sind alle Daten, die auf Sie pers\u00f6nlich beziehbar sind, z. B. Name, Adresse, E-Mail-Adressen, Nutzerverhalten.<\/p>\n<p>(2) Verantwortlicher gem. Art. 4 Abs. 7 EU-Datenschutz-Grundverordnung (DS-GVO) ist<\/p>\n<p>Gerriets GmbH<\/p>\n<p>Im Kirchenh\u00fcrstle 5-7<\/p>\n<p>DE-79224 Umkirch<\/p>\n<p>Telefon: +49 (0)7665 \/ 960-0<\/p>\n<p>E-Mail: <a href=\"mailto:info@gerriets.com\"><span class=\"strrev\" data-link=\"moc.steirreg&#091;ta&#093;ofni:otliam\"><span style=\"color: #3366ff;\">info[at]gerriets.com<\/span><\/span><\/a><\/p>\n<p>Unseren Datenschutzbeauftragten erreichen Sie unter <a href=\"mailto:data-protection@gerriets.com\"><span class=\"strrev\"><span style=\"color: #3366ff;\">data-protection[at]gerriets.com<\/span><\/span><\/a> oder unserer Postadresse mit dem Zusatz \u201eData Protection\u201c.<\/p>\n<p>(3) Bei Ihrer Kontaktaufnahme mit uns per E-Mail oder \u00fcber ein Kontaktformular werden die von Ihnen mitgeteilten Daten (Ihre E-Mail-Adresse, ggf. Ihr Name, Betreff, Nachricht sowie Anregung\/Vorschlag ) von uns gespeichert, um Ihre Fragen zu beantworten. Die in diesem Zusammenhang anfallenden Daten l\u00f6schen wir, nachdem die Speicherung nicht mehr erforderlich ist, oder schr\u00e4nken die Verarbeitung ein, falls gesetzliche Aufbewahrungspflichten bestehen.<\/p>\n<p>(4) Falls wir f\u00fcr einzelne Funktionen unseres Angebots auf beauftragte Dienstleister zur\u00fcckgreifen oder Ihre Daten f\u00fcr werbliche Zwecke nutzen m\u00f6chten, werden wir Sie untenstehend im Detail \u00fcber die jeweiligen Vorg\u00e4nge informieren. Dabei nennen wir auch die festgelegten Kriterien der Speicherdauer.<\/p>\n<p><strong>2 Ihre Rechte<\/strong><\/p>\n<p>(1) Sie haben gegen\u00fcber uns folgende Rechte hinsichtlich der Sie betreffenden personenbezogenen Daten:<\/p>\n<p>\u2013 Recht auf Auskunft,<\/p>\n<p>\u2013 Recht auf Berichtigung oder L\u00f6schung,<\/p>\n<p>\u2013 Recht auf Einschr\u00e4nkung der Verarbeitung,<\/p>\n<p>\u2013 Recht auf Widerspruch gegen die Verarbeitung,<\/p>\n<p>\u2013 Recht auf Daten\u00fcbertragbarkeit.<\/p>\n<p>(2) Sie haben zudem das Recht, sich bei einer Datenschutz-Aufsichtsbeh\u00f6rde \u00fcber die Verarbeitung Ihrer personenbezogenen Daten durch uns zu beschweren.<\/p>\n<p><strong>3 Erhebung personenbezogener Daten bei Besuch unserer Website<\/strong><\/p>\n<p>(1) Bei der blo\u00df informatorischen Nutzung der Website, also wenn Sie sich nicht registrieren oder uns anderweitig Informationen \u00fcbermitteln, erheben wir nur die personenbezogenen Daten, die Ihr Browser an unseren Server \u00fcbermittelt. Wenn Sie unsere Website betrachten m\u00f6chten, erheben wir die folgenden Daten, die f\u00fcr uns technisch erforderlich sind, um Ihnen unsere Website anzuzeigen und die Stabilit\u00e4t und Sicherheit zu gew\u00e4hrleisten (Rechtsgrundlage ist Art. 6 Abs. 1 S. 1 lit. f DS-GVO):<\/p>\n<p>\u2013 IP-Adresse<\/p>\n<div class=\"WordSection2\">\n<p>\u2013 Datum und Uhrzeit der Anfrage<\/p>\n<p>\u2013 Zeitzonendifferenz zur Greenwich Mean Time (GMT)<\/p>\n<p>\u2013 Inhalt der Anforderung (konkrete Seite)<\/p>\n<p>\u2013 Zugriffsstatus\/HTTP-Statuscode<\/p>\n<p>\u2013 jeweils \u00fcbertragene Datenmenge<\/p>\n<p>\u2013 Website, von der die Anforderung kommt<\/p>\n<p>\u2013 Browser<\/p>\n<p>\u2013 Betriebssystem und dessen Oberfl\u00e4che<\/p>\n<p>\u2013 Sprache und Version der Browsersoftware.<\/p>\n<p>(2) Zus\u00e4tzlich zu den zuvor genannten Daten werden bei Ihrer Nutzung unserer Website Cookies auf Ihrem Rechner gespeichert. Bei Cookies handelt es sich um kleine Textdateien, die auf Ihrer Festplatte dem von Ihnen verwendeten Browser zugeordnet gespeichert werden und durch welche der Stelle, die den Cookie setzt (hier durch uns), bestimmte Informationen zuflie\u00dfen. Cookies k\u00f6nnen keine Programme ausf\u00fchren oder Viren auf Ihren Computer \u00fcbertragen. Sie dienen dazu, das Internetangebot insgesamt nutzerfreundlicher und effektiver zu machen.<\/p>\n<p>(3) Einsatz von Cookies:<\/p>\n<p>a) Diese Website nutzt folgende Arten von Cookies, deren Umfang und Funktionsweise im Folgenden erl\u00e4utert werden:<br \/>\n\u2013 Transiente Cookies (dazu b)<br \/>\n\u2013 Persistente Cookies (dazu c).<\/p>\n<p>b) Transiente Cookies werden automatisiert gel\u00f6scht, wenn Sie den Browser schlie\u00dfen.<\/p>\n<p>Dazu z\u00e4hlen insbesondere die Session-Cookies. Diese speichern eine sogenannte Session-ID, mit welcher sich verschiedene Anfragen Ihres Browsers der gemeinsamen Sitzung zuordnen lassen. Dadurch kann Ihr Rechner wiedererkannt werden, wenn Sie auf unsere Website zur\u00fcckkehren. Die Session-Cookies werden gel\u00f6scht, wenn Sie sich ausloggen oder den Browser schlie\u00dfen.<\/p>\n<p>c) Persistente Cookies werden automatisiert nach einer vorgegebenen Dauer gel\u00f6scht, die sich je nach Cookie unterscheiden kann. Sie k\u00f6nnen die Cookies in den Sicherheitseinstellungen Ihres Browsers jederzeit l\u00f6schen.<\/p>\n<p>d) Sie k\u00f6nnen Ihre Browser-Einstellung entsprechend Ihren W\u00fcnschen konfigurieren und z.B. die Annahme von Third-Party-Cookies oder allen Cookies ablehnen. Wir weisen Sie darauf hin, dass Sie eventuell nicht alle Funktionen dieser Website nutzen k\u00f6nnen.<\/p>\n<p><strong>4 Weitere Funktionen und Angebote unserer Website<\/strong><\/p>\n<p>(1) Neben der rein informatorischen Nutzung unserer Website bieten wir verschiedene Leistungen an, die Sie bei Interesse nutzen k\u00f6nnen. Dazu m\u00fcssen Sie in der Regel weitere personenbezogene Daten angeben, die wir zur Erbringung der jeweiligen Leistung nutzen und f\u00fcr die die zuvor genannten Grunds\u00e4tze zur Datenverarbeitung gelten.<\/p>\n<p><strong>5 Widerspruch oder Widerruf gegen die Verarbeitung Ihrer Daten<\/strong><\/p>\n<p>(1) Falls Sie eine Einwilligung zur Verarbeitung Ihrer Daten erteilt haben, k\u00f6nnen Sie diese jederzeit widerrufen. Ein solcher Widerruf beeinflusst die Zul\u00e4ssigkeit der Verarbeitung Ihrer personenbezogenen Daten, nachdem Sie ihn gegen\u00fcber uns ausgesprochen haben.<\/p>\n<p>(2) Soweit wir die Verarbeitung Ihrer personenbezogenen Daten auf die Interessenabw\u00e4gung st\u00fctzen, k\u00f6nnen Sie Widerspruch gegen die Verarbeitung einlegen. Dies ist der Fall, wenn die Verarbeitung insbesondere nicht zur Erf\u00fcllung eines Vertrags mit Ihnen erforderlich ist, was von uns jeweils bei der nachfolgenden Beschreibung der Funktionen dargestellt wird. Bei Aus\u00fcbung eines solchen Widerspruchs bitten wir um Darlegung der Gr\u00fcnde, weshalb wir Ihre personenbezogenen Daten nicht wie von uns durchgef\u00fchrt verarbeiten sollten. Im Falle Ihres begr\u00fcndeten Widerspruchs pr\u00fcfen wir die Sachlage und werden entweder die Datenverarbeitung einstellen bzw. anpassen oder Ihnen unsere zwingenden schutzw\u00fcrdigen Gr\u00fcnde aufzeigen, aufgrund derer wir die Verarbeitung fortf\u00fchren.<\/p>\n<\/div>\n<div class=\"WordSection3\">\n<p>(3) Selbstverst\u00e4ndlich k\u00f6nnen Sie der Verarbeitung Ihrer personenbezogenen Daten f\u00fcr Zwecke der Werbung und Datenanalyse jederzeit widersprechen. \u00dcber Ihren Werbewiderspruch k\u00f6nnen Sie uns unter folgenden Kontaktdaten informieren: datenschutz@ gerriets.com<\/p>\n<p><strong>6 Eingesetzte Werkzeuge zu Web Analytics<\/strong><\/p>\n<p>1. Einsatz von Google Analytics<\/p>\n<p>Zum Zwecke der bedarfsgerechten Gestaltung und fortlaufenden Optimierung unserer Webseiten nutzen wir Google Analytics, einen Webanalysedienst der Google Inc. \u00a0<a href=\"https:\/\/about.google\/intl\/de\/\">https:\/\/about.google\/intl\/de\/<\/a> (1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; im Folgenden \u201eGoogle\u201c). In diesem Zusammenhang werden pseudonymisierte Nutzungsprofile erstellt und Cookies (siehe oben) gesetzt.<\/p>\n<p>Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Webseite, wie Browser-Typ\/-Version, verwendetes Betriebssystem, Referrer-URL (die zuvor besuchte Seite), Hostname des zugreifenden Rechners (IP-Adresse) und die Uhrzeit der Serveranfrage werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Im Falle der Aktivierung der IP-Anonymisierung auf dieser Webseite, wird Ihre IP-Adresse von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Die Informationen werden verwendet, um die Nutzung der Webseite auszuwerten, um Reports \u00fcber die Webseitenaktivit\u00e4ten zusammenzustellen und um weitere mit der Webseitennutzung und der Internetnutzung verbundene Dienstleistungen zu Zwecken der Marktforschung und bedarfsgerechten Gestaltung dieser Webseiten zu erbringen. Die Rechtsgrundlage f\u00fcr den Einsatz von Google Analytics ist Art. 6 Abs. 1 lit. a DSGVO.<\/p>\n<p>Auch werden diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben ist oder soweit Dritte diese Daten im Auftrag verarbeiten. Es wird in keinem Fall Ihre IP-Adresse mit anderen Daten von Google zusammengef\u00fchrt. Die IP-Adressen werden anonymisiert, so dass eine Zuordnung nicht m\u00f6glich ist (sogenanntes IP-Masking).<\/p>\n<p>Die von uns gesendeten und mit Cookies, Nutzerkennungen (z. B. User-ID) oder Werbe-IDs verkn\u00fcpften Daten werden nach 14 Monaten automatisch gel\u00f6scht. Die L\u00f6schung von Daten, deren Aufbewahrungsdauer erreicht ist, erfolgt automatisch einmal im Monat.<\/p>\n<p>Google stellt neue Steuerelemente zur Datenaufbewahrung zur Verf\u00fcgung, sodass zwischen verschiedenen Zeitspannen gew\u00e4hlt werden kann, um die Speicherdauer zu bestimmen (aggregierte Daten sind davon nicht betroffen), jedoch sollte die Speicherdauer auf 14 Monate begrenzt werden, auch wenn Google Analytics eine l\u00e4ngere Speicherdauer erm\u00f6glicht.<\/p>\n<p>N\u00e4here Informationen zu Nutzungsbedingungen und Datenschutz von Google Analytics finden Sie unter: <a href=\"https:\/\/marketingplatform.google.com\/about\/analytics\/terms\/de\/\">https:\/\/marketingplatform.google.com\/about\/analytics\/terms\/de\/<\/a> bzw. unter <a href=\"http:\/\/www.google.com\/intl\/de\/analytics\/privacyoverview.html\">www.google.com\/intl\/de\/analytics\/privacyoverview.html<\/a>.<\/p>\n<p>Sie k\u00f6nnen die Installation und Speicherung von Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen.<\/p>\n<p>Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Webseite bezogenen Daten (inkl. Ihrer IP-Adresse) sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\">tools.google.com\/dlpage\/gaoptout<\/a>.<\/p>\n<\/div>\n<div class=\"WordSection5\">\n<p><strong>7 Eingesetzte Werkzeuge im Bereich Social Media<\/strong><\/p>\n<p>1. Einsatz von Social-Media-Plug-ins<\/p>\n<p>(1) Wir setzen derzeit folgende Social-Media-Plug-ins ein: Facebook , YouTube, Vimeo, LinkedIn, XING . Wir nutzen dabei die sog. Zwei-Klick-L\u00f6sung. Das hei\u00dft, wenn Sie unsere Seite besuchen, werden zun\u00e4chst grunds\u00e4tzlich keine personenbezogenen Daten an die Anbieter der Plug-ins weitergegeben. Den Anbieter des Plug-ins erkennen Sie \u00fcber die Markierung auf dem Kasten \u00fcber seinen Anfangsbuchstaben oder das Logo. Wir er\u00f6ffnen Ihnen die M\u00f6glichkeit, \u00fcber den Button direkt mit dem Anbieter des Plug-ins zu kommunizieren. Nur wenn Sie auf das markierte Feld klicken und es dadurch aktivieren, erh\u00e4lt der Plug-in-Anbieter die Information, dass Sie die entsprechende Website unseres Online-Angebots aufgerufen haben. Zudem werden die unter 3 dieser Erkl\u00e4rung genannten Daten \u00fcbermittelt. Im Fall von Facebook und Xing wird nach Angaben der jeweiligen Anbieter in Deutschland die IP-Adresse sofort nach Erhebung anonymisiert. Durch die Aktivierung des Plug-ins werden also personenbezogene Daten von Ihnen an den jeweiligen Plug-in-Anbieter \u00fcbermittelt und dort (bei US-amerikanischen Anbietern in den USA) gespeichert. Da der Plug-in-Anbieter die Datenerhebung insbesondere \u00fcber Cookies vornimmt, empfehlen wir Ihnen, vor dem Klick auf den ausgegrauten Kasten \u00fcber die Sicherheitseinstellungen Ihres Browsers alle Cookies zu l\u00f6schen.<\/p>\n<p>(2) Wir haben weder Einfluss auf die erhobenen Daten und Datenverarbeitungsvorg\u00e4nge, noch sind uns der volle Umfang der Datenerhebung, die Zwecke der Verarbeitung, die Speicherfristen bekannt. Auch zur L\u00f6schung der erhobenen Daten durch den Plug-in-Anbieter liegen uns keine Informationen vor.<\/p>\n<p>(3) Der Plug-in-Anbieter speichert die \u00fcber Sie erhobenen Daten als Nutzungsprofile und nutzt diese f\u00fcr Zwecke der Werbung, Marktforschung und\/oder bedarfsgerechten Gestaltung seiner Website. Eine solche Auswertung erfolgt insbesondere (auch f\u00fcr nicht eingeloggte Nutzer) zur Darstellung von bedarfsgerechter Werbung und um andere Nutzer des sozialen Netzwerks \u00fcber Ihre Aktivit\u00e4ten auf unserer Website zu informieren. Ihnen steht ein Widerspruchsrecht gegen die Bildung dieser Nutzerprofile zu, wobei Sie sich zur Aus\u00fcbung dessen an den jeweiligen Plug-in-Anbieter wenden m\u00fcssen. \u00dcber die Plug-ins bieten wir Ihnen die M\u00f6glichkeit, mit den sozialen Netzwerken und anderen Nutzern zu interagieren, so dass wir unser Angebot verbessern und f\u00fcr Sie als Nutzer interessanter ausgestalten k\u00f6nnen. Rechtsgrundlage f\u00fcr die Nutzung der Plug-ins ist Art. 6 Abs. 1 S. 1 lit. f DS-GVO.<\/p>\n<p>(4) Die Datenweitergabe erfolgt unabh\u00e4ngig davon, ob Sie ein Konto bei dem Plug-in- Anbieter besitzen und dort eingeloggt sind. Wenn Sie bei dem Plug-in-Anbieter eingeloggt sind, werden Ihre bei uns erhobenen Daten direkt Ihrem beim Plug-in- Anbieter bestehenden Konto zugeordnet. Wenn Sie den aktivierten Button bet\u00e4tigen und z. B. die Seite verlinken, speichert der Plug-in-Anbieter auch diese Information in Ihrem Nutzerkonto und teilt sie Ihren Kontakten \u00f6ffentlich mit. Wir empfehlen Ihnen, sich nach Nutzung eines sozialen Netzwerks regelm\u00e4\u00dfig auszuloggen, insbesondere jedoch vor Aktivierung des Buttons, da Sie so eine Zuordnung zu Ihrem Profil bei dem Plug-in-Anbieter vermeiden k\u00f6nnen.<\/p>\n<p>(5) Weitere Informationen zu Zweck und Umfang der Datenerhebung und ihrer Verarbeitung durch den Plug-in-Anbieter erhalten Sie in den im Folgenden mitgeteilten Datenschutzerkl\u00e4rungen dieser Anbieter. Dort erhalten Sie auch weitere Informationen zu Ihren diesbez\u00fcglichen Rechten und Einstellungsm\u00f6glichkeiten zum Schutze Ihrer Privatsph\u00e4re.<\/p>\n<p>(6) Adressen der jeweiligen Plug-in-Anbieter und URL mit deren Datenschutzhinweisen:<\/p>\n<p>a) [Facebook Inc., 1601 S California Ave, Palo Alto, California 94304, USA: <a href=\"http:\/\/www.facebook.com\/policy.php%20\u037e%20weitere%20Informationen%20zur%20Datenerhebung:\u00a0\">http:\/\/www.facebook.com\/policy.php \u037e weitere Informationen zur Datenerhebung:\u00a0<\/a><a href=\"http:\/\/www.facebook.com\/help\/186325668085084\">http:\/\/www.facebook.com\/help\/186325668085084 , <\/a><a href=\"http:\/\/www.facebook.com\/about\/privacy\/your-info-on-other#applications\">http:\/\/www.facebook.com\/about\/privacy\/your-info-on-other#applications sowie <\/a><a href=\"http:\/\/www.facebook.com\/about\/privacy\/your-info#everyoneinfo\">http:\/\/www.facebook.com\/about\/privacy\/your-info#everyoneinfo .<\/a><\/p>\n<p>b) YouTube, LLC, Cherry Ave., USA: <a href=\"http:\/\/www.google.de\/intl\/de\/policies\/privacy\/\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a><\/p>\n<p>c) Vimeo, LLC, 555 West 18th Street, New York, New York 10011, USA: <a href=\"https:\/\/vimeo.com\/privacy\">https:\/\/vimeo.com\/privacy<\/a><\/p>\n<p>d) LinkedIn Corporation, 2029 Stierlin Court, Mountain View, California 94043, USA: <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/p>\n<p>e) Xing AG, G\u00e4nsemarkt 43, 20354 Hamburg, DE: <a href=\"http:\/\/www.xing.com\/privacy\">http:\/\/www.xing.com\/privacy<\/a><\/p>\n<p>2. AddThis-Bookmarking<\/p>\n<p>(1) Unsere Webseiten enthalten zudem AddThis-Plug-ins. Diese Plug-ins erm\u00f6glichen Ihnen das Setzen von Bookmarks bzw. das Teilen von interessanten Inhalten mit anderen Nutzern. \u00dcber die Plug-ins bieten wir Ihnen die M\u00f6glichkeit, mit den sozialen Netzwerken und anderen Nutzern zu interagieren, so dass wir unser Angebot verbessern und f\u00fcr Sie als Nutzer interessanter ausgestalten k\u00f6nnen. Rechtsgrundlage f\u00fcr die Nutzung der Plug-ins ist Art. 6 Abs. 1 S. 1 lit. f DS-GVO.<\/p>\n<p>(2) \u00dcber diese Plug-ins baut Ihr Internetbrowser eine direkte Verbindung mit den Servern von AddThis und gegebenenfalls dem gew\u00e4hlten sozialen Netzwerk- oder Bookmarking-Dienst auf. Die Empf\u00e4nger erhalten die Information, dass Sie die entsprechende Website unseres Online-Angebots aufgerufen haben und die unter 3 dieser Erkl\u00e4rung genannten Daten. Diese Informationen werden auf den Servern von AddThis in den USA verarbeitet. [Wir haben Standarddatenschutzklauseln mit AddThis abgeschlossen.]. Wenn Sie Inhalte auf unserer Webseite an soziale Netzwerke oder Bookmarking-Dienste senden, kann eine Verbindung zwischen dem Besuch unserer Webseite und Ihrem Nutzerprofil bei dem entsprechenden Netzwerk hergestellt werden. Wir haben weder Einfluss auf die erhobenen Daten und Datenverarbeitungsvorg\u00e4nge, noch sind uns der volle Umfang der Datenerhebung, die Zwecke der Verarbeitung, die Speicherfristen bekannt. Auch zur L\u00f6schung der erhobenen Daten durch den Plug-in-Anbieter liegen uns keine Informationen vor.<\/p>\n<p>(3) Der Plug-in-Anbieter speichert diese Daten als Nutzungsprofile und nutzt diese f\u00fcr Zwecke der Werbung, Marktforschung und\/oder bedarfsgerechten Gestaltung seiner Website. Eine solche Auswertung erfolgt insbesondere (selbst f\u00fcr nicht eingeloggte Nutzer) zur Erbringung von bedarfsgerechter Werbung und um andere Nutzer des sozialen Netzwerks \u00fcber Ihre Aktivit\u00e4ten auf unserer Website zu informieren. Ihnen steht ein Widerspruchsrecht zu gegen die Bildung dieser Nutzerprofile, wobei Sie sich zur Aus\u00fcbung dessen an den jeweiligen Plug-in- Anbieter richten m\u00fcssen.<\/p>\n<p>(4) Wenn Sie nicht an diesem Verfahren teilnehmen m\u00f6chten, k\u00f6nnen Sie der Datenerhebung und -speicherung jederzeit durch Setzen eines Opt -out-Cookies mit Wirkung f\u00fcr die Zukunft widersprechen: <span style=\"color: #3366ff;\">http:\/\/www.addthis.com\/privacy\/opt-out<\/span>. Alternativ k\u00f6nnen Sie Ihren Browser so einstellen, dass er das Setzen eines Cookies verhindert.<\/p>\n<p>(5) Weitere Informationen zu Zweck und Umfang der Datenerhebung und ihrer Verarbeitung durch den Plug-in-Anbieter sowie weitere Informationen zu Ihren diesbez\u00fcglichen Rechten und Einstellungsm\u00f6glichkeiten zum Schutze Ihrer Privatsph\u00e4re erhalten Sie bei: AddThis LLC, 1595 Spring Hill Road, Sweet 300, Vienna, VA 22182, USA, <a class=\"ui-link\" href=\"http:\/\/www.addthis.com\/privacy\"><span style=\"color: #3366ff;\">www.addthis.com\/privacy<\/span>.<\/a><\/p>\n<\/div>\n<div class=\"WordSection6\">\n<p>3. Einbindung von YouTube-Videos bzw. Verweis auf YouTube Channel<\/p>\n<p>(1) Wir haben YouTube-Videos in unser Online-Angebot eingebunden, die auf<span style=\"color: #3366ff;\"><a class=\"ui-link\" style=\"color: #3366ff;\" href=\"http:\/\/www.YouTube.com\"> http:\/\/www.YouTube.com <\/a><\/span> gespeichert sind und von unserer Website aus direkt abspielbar sind. [Diese sind alle im \u201eerweiterten Datenschutz-Modus\u201c eingebunden, d. h. dass keine Daten \u00fcber Sie als Nutzer an YouTube \u00fcbertragen werden, wenn Sie die Videos nicht abspielen. Erst wenn Sie die Videos abspielen, werden die in Absatz 2 genannten Daten \u00fcbertragen. Auf diese Daten\u00fcbertragung haben wir keinen Einfluss.]<\/p>\n<p>(2) Durch den Besuch auf der Website erh\u00e4lt YouTube die Information, dass Sie die entsprechende Unterseite unserer Website aufgerufen haben. Zudem werden die unter 3 dieser Erkl\u00e4rung genannten Daten \u00fcbermittelt. Dies erfolgt unabh\u00e4ngig davon, ob YouTube ein Nutzerkonto bereitstellt, \u00fcber das Sie eingeloggt sind, oder ob kein Nutzerkonto besteht. Wenn Sie bei Google eingeloggt sind, werden Ihre Daten direkt Ihrem Konto zugeordnet. Wenn Sie die Zuordnung mit Ihrem Profil bei YouTube nicht w\u00fcnschen, m\u00fcssen Sie sich vor Aktivierung des Buttons ausloggen. YouTube speichert Ihre Daten als Nutzungsprofile und nutzt sie f\u00fcr Zwecke der Werbung, Marktforschung und\/oder bedarfsgerechten Gestaltung seiner Website. Eine solche Auswertung erfolgt insbesondere (selbst f\u00fcr nicht eingeloggte Nutzer) zur Erbringung von bedarfsgerechter Werbung und um andere Nutzer des sozialen Netzwerks \u00fcber Ihre Aktivit\u00e4ten auf unserer Website zu informieren. Ihnen steht ein Widerspruchsrecht zu gegen die Bildung dieser Nutzerprofile, wobei Sie sich zur Aus\u00fcbung dessen an YouTube richten m\u00fcssen.<\/p>\n<p>(3) Weitere Informationen zu Zweck und Umfang der Datenerhebung und ihrer Verarbeitung durch YouTube erhalten Sie in der Datenschutzerkl\u00e4rung. Dort erhalten Sie auch weitere Informationen zu Ihren Rechten und Einstellungsm\u00f6glichkeiten zum Schutze Ihrer Privatsph\u00e4re: <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\">https:\/\/www.google.de\/intl\/de\/policies\/privacy <\/a><\/p>\n<p>4. Einbindung von Google Maps<\/p>\n<\/div>\n<p>Zur Darstellung der Routen und Ortsangaben verwenden wir auf unserer Webseite verschiedene Dienste der <strong>Google Inc<\/strong> (<a href=\"https:\/\/www.google.de\/intl\/de\/about\/\">https:\/\/www.google.de\/intl\/de\/about\/<\/a>) (1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; im Folgenden \u201eGoogle\u201c). Dies sind im Einzelnen Google Maps, Google Maps Directions, &#8211; Distance, &#8211; Geocoding und &#8211; Geolocation. Diese von Google bereitgestellten Dienste sind jeweils \u00fcber sog. API-Schnittstellen in unsere Webseite eingebunden. Wir, als Anbieter unserer Webseite, haben keine Kenntnis, ob und ggf. welche Daten bei der Nutzung der Google Maps-Dienste an Google \u00fcbertragen werden. F\u00fcr die Nutzung dieser Angebote gelten die Nutzungsbedingungen und Datenschutzbestimmungen von Google die Sie auf der Webseite von Google einsehen k\u00f6nnen. <a href=\"https:\/\/policies.google.com\/privacy?hl=de\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>5. Einbindung von Plugins des Videoportals Vimeo, Vimeo-Channels<\/p>\n<p>(1) Auf unseren Websites sind Plugins des Videoportals Vimeo der Vimeo, LLC, 555<\/p>\n<p>West 18th Street, New York, New York 10011, USA eingebunden. Bei jedem Aufruf einer Seite, die ein oder mehrere Vimeo-Videoclips anbietet, wird eine direkte Verbindung zwischen Ihrem Browser und einem Server von Vimeo in den USA hergestellt. Dabei werden Informationen \u00fcber Ihren Besuch und Ihre IP-Adresse dort gespeichert. Durch Interaktionen mit den Vimeo Plugins (z.B. Klicken des Start-Buttons) werden diese Informationen ebenfalls an Vimeo \u00fcbermittelt und dort gespeichert.<\/p>\n<p>(2) Wenn Sie ein Vimeo-Benutzerkonto haben und nicht m\u00f6chten, dass Vimeo \u00fcber diese Website Daten \u00fcber Sie sammelt und mit Ihren bei Vimeo gespeicherten Mitgliedsdaten verkn\u00fcpft, m\u00fcssen Sie sich vor Ihrem Besuch dieser Website bei Vimeo ausloggen.<\/p>\n<p>(3) Die Datenschutzerkl\u00e4rung f\u00fcr Vimeo mit n\u00e4heren Informationen zur Erhebung und Nutzung Ihrer Daten durch Vimeo finden Sie unter <a href=\"https:\/\/vimeo.com\/privacy\">https:\/\/vimeo.com\/privacy<\/a> .<\/p>\n<p>(4) Au\u00dferdem ruft Vimeo \u00fcber einen iFrame, in dem das Video aufgerufen wird, den Tracker Google Analytics auf. Dabei handelt es sich um ein eigenes Tracking von Vimeo, auf das wir keinen Zugriff haben. Sie k\u00f6nnen das Tracking durch Google Analytics unterbinden, indem Sie die Deaktivierungs-Tools einsetzen, die Google f\u00fcr einige Internet-Browser anbietet. Die Nutzer k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch Google Analytics erzeugten und auf ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren: <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\">https:\/\/tools.google.com\/dlpage\/gaoptout<\/a><\/span><\/p>\n<p>(5) Verschiedene unserer Websites enthalten sogenannte Einbettungen von Videos auf Vimeo oder Videos aus den von uns betriebenen Vimeo-Channels. Diese erm\u00f6glichen jedoch nur die Verbindung zu Vimeo. Wenn Sie Informationen zum Zweck und Umfang der Datenerhebung und -nutzung durch Vimeo, sowie Ihre Rechte und Einstellungsm\u00f6glichkeiten zum Schutz als Vimeo-Kunde erhalten wollen, entnehmen Sie diese bitte den Datenschutzhinweisen von Vimeo (<span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/vimeo.com\/privacy\">https:\/\/vimeo.com\/privacy<\/a><\/span> ).<\/p>\n<\/div>\n\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Datenschutz\u00aderkl\u00e4rung Privatsph\u00e4reneinwilligung Privatsph\u00e4re-Einstellungen \u00e4ndern Historie der Privatsph\u00e4re-Einstellungen Einwilligungen widerrufen 1 Information \u00fcber die Erhebung personenbezogener Daten (1) Im Folgenden informieren wir \u00fcber die Erhebung personenbezogener Daten bei Nutzung unserer Website. Personenbezogene Daten sind alle Daten, die auf Sie pers\u00f6nlich beziehbar sind, z. B. Name, Adresse, E-Mail-Adressen, Nutzerverhalten. (2) Verantwortlicher gem. Art. 4 Abs. 7 EU-Datenschutz-Grundverordnung [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3339","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/pages\/3339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/comments?post=3339"}],"version-history":[{"count":0,"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/pages\/3339\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gerriets-acoustics.com\/pl\/wp-json\/wp\/v2\/media?parent=3339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}